{"id":4965,"date":"2017-07-15T14:37:19","date_gmt":"2017-07-15T12:37:19","guid":{"rendered":"https:\/\/dev.esogetics.org\/wp-content\/uploads\/2017\/06\/20150304_synapsis-wave-home-Handbuch-zum-Drucken-deutsch.pdf"},"modified":"2017-07-15T14:37:19","modified_gmt":"2017-07-15T12:37:19","slug":"20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2","status":"inherit","type":"attachment","link":"https:\/\/esogetics.com\/en\/20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2\/","title":{"rendered":"20150304_synapsis wave + home Handbuch zum Drucken deutsch"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false},"class_list":["post-4965","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>20150304_synapsis wave + home Handbuch zum Drucken deutsch - Esogetics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esogetics.com\/en\/20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20150304_synapsis wave + home Handbuch zum Drucken deutsch - Esogetics\" \/>\n<meta property=\"og:description\" content=\"20150304_synapsis wave + home Handbuch zum Drucken deutsch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esogetics.com\/en\/20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Esogetics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esogetics.com\\\/en\\\/20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2\\\/\",\"url\":\"https:\\\/\\\/esogetics.com\\\/en\\\/20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2\\\/\",\"name\":\"20150304_synapsis wave + home Handbuch zum Drucken deutsch - Esogetics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esogetics.com\\\/en\\\/#website\"},\"datePublished\":\"2017-07-15T12:37:19+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esogetics.com\\\/en\\\/20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esogetics.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/esogetics.com\\\/en\\\/\",\"name\":\"Esogetics\",\"description\":\"Die Heilkraft der Farben\",\"publisher\":{\"@id\":\"https:\\\/\\\/esogetics.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esogetics.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esogetics.com\\\/en\\\/#organization\",\"name\":\"Esogetics\",\"url\":\"https:\\\/\\\/esogetics.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/esogetics.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dev.esogetics.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-esofetics.png\",\"contentUrl\":\"https:\\\/\\\/dev.esogetics.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-esofetics.png\",\"width\":300,\"height\":262,\"caption\":\"Esogetics\"},\"image\":{\"@id\":\"https:\\\/\\\/esogetics.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20150304_synapsis wave + home Handbuch zum Drucken deutsch - Esogetics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esogetics.com\/en\/20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2\/","og_locale":"en_US","og_type":"article","og_title":"20150304_synapsis wave + home Handbuch zum Drucken deutsch - Esogetics","og_description":"20150304_synapsis wave + home Handbuch zum Drucken deutsch","og_url":"https:\/\/esogetics.com\/en\/20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2\/","og_site_name":"Esogetics","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/esogetics.com\/en\/20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2\/","url":"https:\/\/esogetics.com\/en\/20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2\/","name":"20150304_synapsis wave + home Handbuch zum Drucken deutsch - Esogetics","isPartOf":{"@id":"https:\/\/esogetics.com\/en\/#website"},"datePublished":"2017-07-15T12:37:19+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esogetics.com\/en\/20150304_synapsis-wave-home-handbuch-zum-drucken-deutsch-2\/"]}]},{"@type":"WebSite","@id":"https:\/\/esogetics.com\/en\/#website","url":"https:\/\/esogetics.com\/en\/","name":"Esogetics","description":"Die Heilkraft der Farben","publisher":{"@id":"https:\/\/esogetics.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esogetics.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/esogetics.com\/en\/#organization","name":"Esogetics","url":"https:\/\/esogetics.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/esogetics.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dev.esogetics.org\/wp-content\/uploads\/2025\/02\/logo-esofetics.png","contentUrl":"https:\/\/dev.esogetics.org\/wp-content\/uploads\/2025\/02\/logo-esofetics.png","width":300,"height":262,"caption":"Esogetics"},"image":{"@id":"https:\/\/esogetics.com\/en\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/esogetics.com\/wp-content\/uploads\/2017\/06\/20150304_synapsis-wave-home-Handbuch-zum-Drucken-deutsch.pdf'>20150304_synapsis wave + home Handbuch zum Drucken deutsch<\/a><\/p>\n"},"caption":{"rendered":"<p>20150304_synapsis wave + home Handbuch zum Drucken deutsch<\/p>\n"},"alt_text":"","media_type":"file","mime_type":"application\/pdf","media_details":{"filesize":581214,"sizes":{}},"post":null,"source_url":"https:\/\/esogetics.com\/wp-content\/uploads\/2017\/06\/20150304_synapsis-wave-home-Handbuch-zum-Drucken-deutsch.pdf","_links":{"self":[{"href":"https:\/\/esogetics.com\/en\/wp-json\/wp\/v2\/media\/4965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esogetics.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/esogetics.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/esogetics.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/esogetics.com\/en\/wp-json\/wp\/v2\/comments?post=4965"}]}}